{"id":900,"date":"2017-07-18T16:28:51","date_gmt":"2017-07-18T16:28:51","guid":{"rendered":"http:\/\/blog.platiniumhost.com\/?p=900"},"modified":"2017-07-18T16:28:51","modified_gmt":"2017-07-18T16:28:51","slug":"el-onceavo-dedo","status":"publish","type":"post","link":"https:\/\/platiniumhost.com\/blog\/el-onceavo-dedo\/","title":{"rendered":"El onceavo dedo"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El onceavo dedo:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mucho se ha dicho sobre los or\u00edgenes utilitarios de nuestros dedos pulgares desde el campo de la ciencias y un tanto m\u00e1s sobre c\u00f3mo estos determinaron el avance de la raza humana por sobre las dem\u00e1s especies. Hoy por hoy desde el campo de las artes tambi\u00e9n se teoriza y se incide sobre nuestras posibles evoluciones corporales ya que Dani Clode, una graduada de Royal Collage of Art ha llevado todo un paso m\u00e1s hacia el futuro, con la creaci\u00f3n de un tercer dedo pulgar rob\u00f3tico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La autora de esta peculiar creaci\u00f3n, se ha inspirado en la base semi\u00f3tica de la palabra \u201cpr\u00f3tesis\u201d, entendida como una adici\u00f3n de algo, para desarrollar un pulgar rob\u00f3tico port\u00e1til sin intenciones de sustituir a un dedo perdido, sino de darle once dedos a su usuario y ver qu\u00e9 suced\u00eda, este tercer pulgar es un dedo adicional motorizado, controlable, dise\u00f1ado para cualquier persona que desee extender sus capacidades naturales, funciona mediante un elaborado sistema de bater\u00edas, sistemas de comunicaci\u00f3n bluetooth y motores que hacen posible la ejecuci\u00f3n de varias tareas, desde operar una Tablet o repartir cartas, hasta tocar una guitarra.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cole concibe su creaci\u00f3n m\u00e1s all\u00e1 de fines terap\u00e9uticos o funcionales y nos lo muestra como una herramienta y una experiencia catalizadora para que la sociedad considere el uso de extensiones humanas. El tercer pulgar es controlado por el movimiento de los pies del usuario, a trav\u00e9s de sensores de presi\u00f3n incrustados en sus zapatos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Clode eligi\u00f3 este m\u00e9todo de control para explotar las conexiones existentes entre las manos y los pies, que empleamos regularmente cuando manejamos un coche, operamos una m\u00e1quina de coser o tocamos un piano.<\/span><\/p>\n<h2>Transmisi\u00f3n de Biometr\u00eda y Cifrado Perimetral<\/h2>\n<p>Los avances en pr\u00f3tesis bi\u00f3nicas y biometr\u00eda dependen de la transferencia segura de datos sensoriales. A nivel de infraestructura web, el manejo de esta informaci\u00f3n exige certificados SSL avanzados. PlatiniumHost asegura la confidencialidad de tus plataformas corporativas mediante cifrado automatizado Let&#8217;s Encrypt de extremo a extremo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El onceavo dedo: Mucho se ha dicho sobre los or\u00edgenes utilitarios de nuestros dedos pulgares desde el campo de la ciencias y un tanto m\u00e1s sobre c\u00f3mo estos determinaron el avance de la raza humana por sobre las dem\u00e1s especies. Hoy por hoy desde el campo de las artes tambi\u00e9n se teoriza y se incide&#8230;<\/p>\n","protected":false},"author":1,"featured_media":901,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[146,147,82,74],"class_list":["post-900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-informatica","tag-protesis","tag-robotica","tag-tecnologia"],"_links":{"self":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/posts\/900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/comments?post=900"}],"version-history":[{"count":0,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/posts\/900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/media\/901"}],"wp:attachment":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/media?parent=900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/categories?post=900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/tags?post=900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}