{"id":1255,"date":"2018-09-16T10:56:14","date_gmt":"2018-09-16T10:56:14","guid":{"rendered":"https:\/\/blog.platiniumhost.com\/?p=1255"},"modified":"2018-09-14T20:05:14","modified_gmt":"2018-09-14T20:05:14","slug":"asi-es-el-nuevo-apple-watch-series-4","status":"publish","type":"post","link":"https:\/\/platiniumhost.com\/blog\/asi-es-el-nuevo-apple-watch-series-4\/","title":{"rendered":"As\u00ed es el nuevo Apple Watch Series 4"},"content":{"rendered":"<p style=\"text-align: justify;\">Apple ha presentado la cuarta generaci\u00f3n de sus relojes inteligentes, el <strong>Apple Watch Series 4<\/strong>, que vendr\u00e1 en dos tama\u00f1os, de 40 y 44 mil\u00edmetros, es decir, ligeramente m\u00e1s grandes que sus predecesores, de 38 y 40 mil\u00edmetros. Ambos modelos tendr\u00e1n paneles de tipo OLED de dise\u00f1o cuadrado. Adem\u00e1s de sistema de geoposicionamiento por GPS, uno de ellos contar\u00e1 con conectividad para redes de telefon\u00eda, lo que podr\u00e1 utilizarse sin estar conectado obligatoriamente con el iPhone. Su idea, convertirse en un \u00abgadget\u00bb para la salud.<\/p>\n<p style=\"text-align: justify;\">El chasis, <strong>m\u00e1s liviano y ligero que el anterior modelo<\/strong>, le confiere un aire de modernidad y elegancia. Aumentar sus dimensiones, adem\u00e1s, ha permitido mostrar m\u00e1s informaci\u00f3n. A nivel est\u00e9tico, el dispositivo se ha estilizado gracias a sus bordes ligeramente m\u00e1s redondeados. Ha ganado espacio (un 32%) pero se mantiene la idea conpcetual. \u00abEs el reloj m\u00e1s vendido del mundo, no solo el \u00absmartwatch\u00bb\u00bb, apostill\u00f3<strong> Tim Cook<\/strong>, consejero delegado de Apple, durante su presentaci\u00f3n este mi\u00e9rcoles en su sede oficial.<\/p>\n<p style=\"text-align: justify;\">Para ello, se ha redise\u00f1ado su interfaz para lograr a\u00f1adir m\u00e1s informaci\u00f3n de la actividad f\u00edsica, de notificaciones y dem\u00e1s funciones personales. \u00abEs un guardi\u00e1n de la salud\u00bb, defendi\u00f3 <strong>Jeff Williams<\/strong>, director de operaciones de Apple, quien adelant\u00f3 que el nuevo dispositivo ser\u00e1 capaz, adem\u00e1s, de detectar ca\u00eddas bruscas. Si el dispositivo detecta inmovilidad<strong> durante 60 segundos <\/strong>tras la notificaci\u00f3n, llamar\u00e1 autom\u00e1ticamente a los servicios de urgencias y enviar\u00e1 un mensaje con la ubicaci\u00f3n a los contactos de emergencia. Para detectar las ca\u00eddas, se utilizan un aceler\u00f3metro y un giroscopio de \u00faltima generaci\u00f3n, as\u00ed como algoritmos creados espec\u00edficamente para identificar las ca\u00eddas. El objetivo es analizar la trayectoria de la mu\u00f1eca y la aceleraci\u00f3n del impacto.<\/p>\n<aside class=\"roba-intercalado sin-fondo layer_inpage\"><span id=\"layer_inpage-id\" class=\"creatividad cmv_intext\" data-voc-vam=\"\" data-voc-vam-position=\"layer_inpage\" data-voc-vam-outofpage=\"true\"><\/span><\/aside>\n<p style=\"text-align: justify;\">Adem\u00e1s de mayor potencia gracias al nuevo procesador S4, dispone <strong>de un enfoque muy orientado al an\u00e1lisis y monitorizaci\u00f3n de la salud,<\/strong> contando para ello con un nuevo sensor de ritmo c\u00e1rdiaco, que se ha mejorado en esta ocasi\u00f3n. El nuevo modelo ser\u00e1 capaz de detectar alguna anomal\u00eda en el pulso del usuario. Unos nuevos sensores permitir\u00e1n al Apple Watch realizar electrocardiograma. Unos valores importantes para aquellas personas que tienen alg\u00fan problema coronario, permitiendo, adem\u00e1s, compartir la informaci\u00f3n con un profesional m\u00e9dico.<\/p>\n<p style=\"text-align: justify;\">Otra de sus apuestas es ampliar el cat\u00e1logo de esferas digitales o pantallas principales. <strong>Una de ellas est\u00e1 dise\u00f1ada para a\u00f1adir im\u00e1genes personales.<\/strong> Adem\u00e1s de estas novedades, el dispositivo ha mejorado el equipo de audio del altavoz, el doble de potente que el anterior. Pese al cambio est\u00e9tico, las correas ser\u00e1n compatibles. La parte trasera del Apple Watch Series 4 est\u00e1 compuesta de cer\u00e1mica negra y cristal de zafiro, mientras que la corona (Digital Crown) incluye ahora respuesta h\u00e1ptica, con peque\u00f1as vibraciones, y que sirve como punto de medici\u00f3n secundaria para realizar ese electrocardiograma. El \u00abwearable\u00bb debutar\u00e1 con el sistema operativo WatchOS 5, que mejora las notificaciones, una nueva aplicaci\u00f3n de entrenamiento o competiciones entre contactos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apple ha presentado la cuarta generaci\u00f3n de sus relojes inteligentes, el Apple Watch Series 4, que vendr\u00e1 en dos tama\u00f1os, de 40 y 44 mil\u00edmetros, es decir, ligeramente m\u00e1s grandes que sus predecesores, de 38 y 40 mil\u00edmetros. Ambos modelos tendr\u00e1n paneles de tipo OLED de dise\u00f1o cuadrado. Adem\u00e1s de sistema de geoposicionamiento por GPS,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[377,375,378,376],"class_list":["post-1255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-acelerometro","tag-apple-watch","tag-dispositivo","tag-geoposicionamiento"],"_links":{"self":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/posts\/1255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/comments?post=1255"}],"version-history":[{"count":0,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/posts\/1255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/media\/1256"}],"wp:attachment":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/media?parent=1255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/categories?post=1255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/tags?post=1255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}