{"id":1154,"date":"2018-04-03T15:15:02","date_gmt":"2018-04-03T15:15:02","guid":{"rendered":"https:\/\/blog.platiniumhost.com\/?p=1154"},"modified":"2018-04-02T15:18:03","modified_gmt":"2018-04-02T15:18:03","slug":"china-y-francia-lanzaran-en-septiembre-un-satelite-de-observacion-oceanica","status":"publish","type":"post","link":"https:\/\/platiniumhost.com\/blog\/china-y-francia-lanzaran-en-septiembre-un-satelite-de-observacion-oceanica\/","title":{"rendered":"China y Francia lanzar\u00e1n en septiembre un sat\u00e9lite de observaci\u00f3n oce\u00e1nica"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>China y Francia lanzar\u00e1n conjuntamente en septiembre un sat\u00e9lite para la investigaci\u00f3n de los oc\u00e9anos<\/strong>\u00a0con el que pretenden facilitar la implementaci\u00f3n de los Acuerdos de Par\u00eds sobre el cambio clim\u00e1tico, inform\u00f3 hoy la agencia estatal Xinhua.<span id=\"more-26800\"><\/span><\/p>\n<p style=\"text-align: justify;\">Se trata del primer sat\u00e9lite que ambos pa\u00edses impulsan conjuntamente y permitir\u00e1 mejorar la cooperaci\u00f3n tecnol\u00f3gica bilateral, seg\u00fan la Academia de Lanzamiento de Tecnolog\u00eda de Veh\u00edculos de China (CALT), encargada de desarrollar el aparato.<\/p>\n<p style=\"text-align: justify;\"><strong>El sat\u00e9lite se encargar\u00e1 de controlar los vientos y las olas en la superficie de los oc\u00e9anos,<\/strong>\u00a0y los datos que recopile ser\u00e1n compartidos por cient\u00edficos chinos y franceses.<\/p>\n<p style=\"text-align: justify;\">El acuerdo para lanzar conjuntamente este sat\u00e9lite fue anunciado el pasado enero durante la primera visita oficial a China del presidente de Francia, Emmanuel Macron.<\/p>\n<h2>Procesamiento Masivo de Datos y Almacenamiento NVMe<\/h2>\n<p>Los equipos de observaci\u00f3n generan y transmiten terabytes de telemetr\u00eda diariamente. Recibir, almacenar y procesar esta informaci\u00f3n exige una infraestructura de red robusta con velocidades de lectura y escritura ultrarr\u00e1pidas.<\/p>\n<p>A escala corporativa, las empresas que manejan an\u00e1lisis de big data o repositorios masivos enfrentan desaf\u00edos similares. Los discos mec\u00e1nicos tradicionales representan un cuello de botella inaceptable para estas operaciones.<\/p>\n<p>Todos los nodos de Web Hosting, VPS y Servidores Dedicados en PlatiniumHost operan exclusivamente con unidades de estado s\u00f3lido NVMe. Esto asegura que el procesamiento de grandes vol\u00famenes de informaci\u00f3n o consultas SQL pesadas se ejecuten con una latencia de milisegundos, manteniendo la integridad de los datos en tiempo real.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>China y Francia lanzar\u00e1n conjuntamente en septiembre un sat\u00e9lite para la investigaci\u00f3n de los oc\u00e9anos\u00a0con el que pretenden facilitar la implementaci\u00f3n de los Acuerdos de Par\u00eds sobre el cambio clim\u00e1tico, inform\u00f3 hoy la agencia estatal Xinhua. Se trata del primer sat\u00e9lite que ambos pa\u00edses impulsan conjuntamente y permitir\u00e1 mejorar la cooperaci\u00f3n tecnol\u00f3gica bilateral, seg\u00fan la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1155,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[9],"tags":[137,132,328,329],"class_list":["post-1154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","tag-china","tag-clima","tag-francia","tag-oceanos"],"_links":{"self":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/posts\/1154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/comments?post=1154"}],"version-history":[{"count":0,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/posts\/1154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/media\/1155"}],"wp:attachment":[{"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/media?parent=1154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/categories?post=1154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/platiniumhost.com\/blog\/wp-json\/wp\/v2\/tags?post=1154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}